{"id":2001,"date":"2017-03-15T16:06:39","date_gmt":"2017-03-15T16:06:39","guid":{"rendered":"http:\/\/www.deliciousandsons.com\/blog\/porridge-trendy-healthy\/"},"modified":"2017-04-08T14:47:24","modified_gmt":"2017-04-08T14:47:24","slug":"porridge-moda-receta-saludable","status":"publish","type":"post","link":"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/","title":{"rendered":"Porridge: moda o receta saludable?"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":1993,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[333,2],"tags":[],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Porridge moda o receta saludable? | Delicious &amp; Sons<\/title>\n<meta name=\"description\" content=\"El porridge, elaborado con avena se llama oatmeal, es de los platos m\u00e1s fotografiados en Instagram, pero hay algo de valor nutricional o solo es una moda?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Porridge moda o receta saludable? | Delicious &amp; Sons\" \/>\n<meta property=\"og:description\" content=\"El porridge, elaborado con avena se llama oatmeal, es de los platos m\u00e1s fotografiados en Instagram, pero hay algo de valor nutricional o solo es una moda?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/\" \/>\n<meta property=\"og:site_name\" content=\"Delicious &amp; Sons\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DeliciousandSons\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-15T16:06:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-08T14:47:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deliciousandsons.com\/wp-content\/uploads\/2017\/03\/porridge-foto-1a-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricky Mandle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Delicious_Sons\" \/>\n<meta name=\"twitter:site\" content=\"@Delicious_Sons\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricky Mandle\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/\",\"url\":\"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/\",\"name\":\"Porridge moda o receta saludable? | Delicious & Sons\",\"isPartOf\":{\"@id\":\"https:\/\/www.deliciousandsons.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.deliciousandsons.com\/wp-content\/uploads\/2017\/03\/porridge-foto-1a-scaled.jpg\",\"datePublished\":\"2017-03-15T16:06:39+00:00\",\"dateModified\":\"2017-04-08T14:47:24+00:00\",\"author\":{\"@id\":\"https:\/\/www.deliciousandsons.com\/#\/schema\/person\/5c11003c721516eaf1d77b0ab6689433\"},\"description\":\"El porridge, elaborado con avena se llama oatmeal, es de los platos m\u00e1s fotografiados en Instagram, pero hay algo de valor nutricional o solo es una moda?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/#primaryimage\",\"url\":\"https:\/\/www.deliciousandsons.com\/wp-content\/uploads\/2017\/03\/porridge-foto-1a-scaled.jpg\",\"contentUrl\":\"https:\/\/www.deliciousandsons.com\/wp-content\/uploads\/2017\/03\/porridge-foto-1a-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"porridge por delicious & sons\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.deliciousandsons.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Porridge: moda o receta saludable?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.deliciousandsons.com\/#website\",\"url\":\"https:\/\/www.deliciousandsons.com\/\",\"name\":\"Delicious &amp; Sons\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.deliciousandsons.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.deliciousandsons.com\/#\/schema\/person\/5c11003c721516eaf1d77b0ab6689433\",\"name\":\"Ricky Mandle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.deliciousandsons.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/610aa254e6e47b85ec337ddc625416c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/610aa254e6e47b85ec337ddc625416c9?s=96&d=mm&r=g\",\"caption\":\"Ricky Mandle\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Porridge moda o receta saludable? | Delicious & Sons","description":"El porridge, elaborado con avena se llama oatmeal, es de los platos m\u00e1s fotografiados en Instagram, pero hay algo de valor nutricional o solo es una moda?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/","og_locale":"es_ES","og_type":"article","og_title":"Porridge moda o receta saludable? | Delicious & Sons","og_description":"El porridge, elaborado con avena se llama oatmeal, es de los platos m\u00e1s fotografiados en Instagram, pero hay algo de valor nutricional o solo es una moda?","og_url":"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/","og_site_name":"Delicious &amp; Sons","article_publisher":"https:\/\/www.facebook.com\/DeliciousandSons\/","article_published_time":"2017-03-15T16:06:39+00:00","article_modified_time":"2017-04-08T14:47:24+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/www.deliciousandsons.com\/wp-content\/uploads\/2017\/03\/porridge-foto-1a-scaled.jpg","type":"image\/jpeg"}],"author":"Ricky Mandle","twitter_card":"summary_large_image","twitter_creator":"@Delicious_Sons","twitter_site":"@Delicious_Sons","twitter_misc":{"Escrito por":"Ricky Mandle"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/","url":"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/","name":"Porridge moda o receta saludable? | Delicious & Sons","isPartOf":{"@id":"https:\/\/www.deliciousandsons.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/#primaryimage"},"image":{"@id":"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deliciousandsons.com\/wp-content\/uploads\/2017\/03\/porridge-foto-1a-scaled.jpg","datePublished":"2017-03-15T16:06:39+00:00","dateModified":"2017-04-08T14:47:24+00:00","author":{"@id":"https:\/\/www.deliciousandsons.com\/#\/schema\/person\/5c11003c721516eaf1d77b0ab6689433"},"description":"El porridge, elaborado con avena se llama oatmeal, es de los platos m\u00e1s fotografiados en Instagram, pero hay algo de valor nutricional o solo es una moda?","breadcrumb":{"@id":"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/#primaryimage","url":"https:\/\/www.deliciousandsons.com\/wp-content\/uploads\/2017\/03\/porridge-foto-1a-scaled.jpg","contentUrl":"https:\/\/www.deliciousandsons.com\/wp-content\/uploads\/2017\/03\/porridge-foto-1a-scaled.jpg","width":1920,"height":2560,"caption":"porridge por delicious & sons"},{"@type":"BreadcrumbList","@id":"https:\/\/www.deliciousandsons.com\/es\/blog\/porridge-moda-receta-saludable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.deliciousandsons.com\/es\/"},{"@type":"ListItem","position":2,"name":"Porridge: moda o receta saludable?"}]},{"@type":"WebSite","@id":"https:\/\/www.deliciousandsons.com\/#website","url":"https:\/\/www.deliciousandsons.com\/","name":"Delicious &amp; Sons","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deliciousandsons.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.deliciousandsons.com\/#\/schema\/person\/5c11003c721516eaf1d77b0ab6689433","name":"Ricky Mandle","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.deliciousandsons.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/610aa254e6e47b85ec337ddc625416c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/610aa254e6e47b85ec337ddc625416c9?s=96&d=mm&r=g","caption":"Ricky Mandle"}}]}},"_links":{"self":[{"href":"https:\/\/www.deliciousandsons.com\/es\/wp-json\/wp\/v2\/posts\/2001"}],"collection":[{"href":"https:\/\/www.deliciousandsons.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deliciousandsons.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deliciousandsons.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deliciousandsons.com\/es\/wp-json\/wp\/v2\/comments?post=2001"}],"version-history":[{"count":9,"href":"https:\/\/www.deliciousandsons.com\/es\/wp-json\/wp\/v2\/posts\/2001\/revisions"}],"predecessor-version":[{"id":2044,"href":"https:\/\/www.deliciousandsons.com\/es\/wp-json\/wp\/v2\/posts\/2001\/revisions\/2044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deliciousandsons.com\/es\/wp-json\/wp\/v2\/media\/1993"}],"wp:attachment":[{"href":"https:\/\/www.deliciousandsons.com\/es\/wp-json\/wp\/v2\/media?parent=2001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deliciousandsons.com\/es\/wp-json\/wp\/v2\/categories?post=2001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deliciousandsons.com\/es\/wp-json\/wp\/v2\/tags?post=2001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}